{"id":22105,"date":"2021-06-11T19:50:09","date_gmt":"2021-06-11T22:50:09","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=22105"},"modified":"2021-06-12T12:35:22","modified_gmt":"2021-06-12T15:35:22","slug":"hallaron-sin-vida-a-una-joven-en-la-estancia-las-gamitas-de-golondrina","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/06\/11\/hallaron-sin-vida-a-una-joven-en-la-estancia-las-gamitas-de-golondrina\/","title":{"rendered":"Hallaron sin vida a una joven en la estancia Las Gamitas de Golondrina"},"content":{"rendered":"<p><strong>Celeste Jolyot, de 29 a\u00f1os, fue hallada sin vida en la estancia ubicada en el distrito Golondrina, donde trabajaba.<\/strong><\/p>\n<p>En horas de la siesta de este viernes, la joven docente de ingl\u00e9s fue encontrada ahorcada como consecuencia de su decisi\u00f3n de terminar con su vida.<\/p>\n<p>Era oriunda de Intiyaco pero ten\u00eda residencia en Avellaneda.<\/p>\n<p>En el lugar trabaj\u00f3 personal policial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celeste Jolyot, de 29 a\u00f1os, fue hallada sin vida en la estancia ubicada en el distrito Golondrina, donde trabajaba. En horas de la siesta de este viernes, la joven docente de ingl\u00e9s fue encontrada ahorcada como consecuencia de su decisi\u00f3n de terminar con su vida. Era oriunda de Intiyaco pero ten\u00eda residencia en Avellaneda. En [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51,30],"tags":[],"class_list":["post-22105","post","type-post","status-publish","format-standard","has-post-thumbnail","category-locales","category-policiales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/22105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=22105"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/22105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/22107"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=22105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=22105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=22105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}