{"id":21141,"date":"2021-05-25T06:39:17","date_gmt":"2021-05-25T09:39:17","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=21141"},"modified":"2021-05-25T20:01:55","modified_gmt":"2021-05-25T23:01:55","slug":"verenses-autoconvocados-marcharan-contra-las-restricciones","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/05\/25\/verenses-autoconvocados-marcharan-contra-las-restricciones\/","title":{"rendered":"Verenses autoconvocados marchar\u00e1n contra las restricciones"},"content":{"rendered":"<p><strong>La movilizaci\u00f3n est\u00e1 prevista para hoy a las 16.<\/strong><\/p>\n<p>El colectivo denominado Verenses Autoconvocados se movilizar\u00e1 esta tarde para reclamar el cese de las prohibiciones para trabajar libremente<\/p>\n<p>La marcha que estaba programada en principio para las 10, fue fijada finalmente para las 16 de manera que coincida con la protesta a nivel a nacional.<\/p>\n<p>Los manifestantes, en su mayor\u00eda comerciantes, se concentrar\u00e1n en Plaza Independencia para luego encaminarse a la sede municipal.<\/p>\n<p>La consigna es Necesitamos Trabajar y se pide asistir con barbijo, respetando el distanciamiento social y, en lo posible, en veh\u00edculos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La movilizaci\u00f3n est\u00e1 prevista para hoy a las 16. El colectivo denominado Verenses Autoconvocados se movilizar\u00e1 esta tarde para reclamar el cese de las prohibiciones para trabajar libremente La marcha que estaba programada en principio para las 10, fue fijada finalmente para las 16 de manera que coincida con la protesta a nivel a nacional. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":21143,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":{"0":"post-21141","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-vera"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/21141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=21141"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/21141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/21143"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=21141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=21141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=21141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}