{"id":21134,"date":"2021-05-24T22:36:01","date_gmt":"2021-05-25T01:36:01","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=21134"},"modified":"2021-05-24T22:36:01","modified_gmt":"2021-05-25T01:36:01","slug":"hubo-4-fallecidos-en-la-region-reconquista","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/05\/24\/hubo-4-fallecidos-en-la-region-reconquista\/","title":{"rendered":"Hubo 4 fallecidos en la regi\u00f3n Reconquista"},"content":{"rendered":"<p><strong>La Regi\u00f3n de Salud Reconquista inform\u00f3 a la poblaci\u00f3n que este lunes 24 de mayo se reportaron 121 casos de Covid-19 positivo: <\/strong><\/p>\n<p>8 Florencia; 3 Hardy; 4 Las Toscas; 1 San Antonio de Obligado; 10 Villa Ocampo; 1 Ingeniero Chanourdi\u00e9 (Los Lapachos); 21 Avellaneda; 44 Reconquista; 20 Malabrigo; 3 Los Laureles; 6 Romang.<\/p>\n<p>Total de casos activos en la regi\u00f3n: 1253 (1193 cumpliendo aislamientos domiciliario obligatorio con vigilancia epidemiol\u00f3gica, 60 internados).<\/p>\n<p><strong>Fallecidos<\/strong><\/p>\n<p>Se informa el fallecimiento, en el d\u00eda de la fecha, de cuatro personas con diagn\u00f3stico positivo de coronavirus (2019-nCoV).<\/p>\n<p>&#8211; 1 paciente (51 a\u00f1os) con residencia en Malabrigo.<br \/>\n&#8211; 1 paciente (82 a\u00f1os) con residencia en Romang.<br \/>\n&#8211; 1 paciente (55 a\u00f1os) con residencia en Hardy.<br \/>\n&#8211; 1 paciente (60 a\u00f1os) con residencia en Reconquista<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Regi\u00f3n de Salud Reconquista inform\u00f3 a la poblaci\u00f3n que este lunes 24 de mayo se reportaron 121 casos de Covid-19 positivo: 8 Florencia; 3 Hardy; 4 Las Toscas; 1 San Antonio de Obligado; 10 Villa Ocampo; 1 Ingeniero Chanourdi\u00e9 (Los Lapachos); 21 Avellaneda; 44 Reconquista; 20 Malabrigo; 3 Los Laureles; 6 Romang. Total de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55],"tags":[],"class_list":{"0":"post-21134","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-reconquista"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/21134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=21134"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/21134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/20873"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=21134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=21134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=21134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}