{"id":20583,"date":"2021-05-13T18:32:53","date_gmt":"2021-05-13T21:32:53","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=20583"},"modified":"2021-05-13T18:32:53","modified_gmt":"2021-05-13T21:32:53","slug":"recompensa-de-un-millon-de-pesos-para-quienes-hallaron-a-rosalia-jara","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/05\/13\/recompensa-de-un-millon-de-pesos-para-quienes-hallaron-a-rosalia-jara\/","title":{"rendered":"Recompensa de un mill\u00f3n de pesos para quienes hallaron a Rosal\u00eda Jara"},"content":{"rendered":"<p><strong>La joven madre de Fort\u00edn Olmos fue asesinada el 1 de julio de 2017, hecho por el cual fue condenado a prisi\u00f3n perpetua el profesor Juan Vald\u00e9z.<\/strong><\/p>\n<p>El Gobierno dispuso el pago de un mill\u00f3n de pesos para Gustavo Daniel Monz\u00f3n y a Jos\u00e9 Orlando Stefanucci en virtud de haber aportado &#8220;datos \u00fatiles, relevantes y decisivos&#8221; para encontrar los restos de Rosal\u00eda Daniela Jara, la joven de Fort\u00edn Olmos asesinada el 1 de julio de 2017, hecho por el cual fue condenado a prisi\u00f3n perpetua el profesor Juan Vald\u00e9z.<\/p>\n<p>Con firma del ministro de Gobierno, Justicia, Derechos Humanos y Diversidad, Roberto Sukerman, la resoluci\u00f3n N\u00b0 170 establece\u00a0que el mill\u00f3n de pesos debe\u00a0repartirse\u00a0en dos partes iguales de $500.000 entre Monz\u00f3n y Stefanucci.<\/p>\n<p>Los restos \u00f3seos de Rosal\u00eda Jara fueron\u00a0encontrados\u00a0en el campo del reconquistense Mario Braida, cerca del Arroyo &#8220;El Bonete&#8221;, al costado de la Ruta Nacional 98, dentro del Departamento Vera. Cotejados los ADN con su hija y su madre, se pudo\u00a0determinar\u00a0que pertenecieron al cuerpo de la v\u00edctima.<\/p>\n<p>Gustavo Monz\u00f3n cont\u00f3 que fue quien primero ingres\u00f3 al campo de Braida a cazar lugar donde encontr\u00f3 los restos \u00f3seos que r\u00e1pidamente descart\u00f3 como pertenecientes a cualquier tipo de animal. Al encontrar un cr\u00e1neo humano, llam\u00f3 a su compa\u00f1ero y procedieron a dar aviso a la polic\u00eda rural de Las Gamas. Ambos dijeron que conoc\u00edan que Jara permanec\u00eda desaparecida, pero nunca imaginaron que pod\u00eda tratarse de ella.<\/p>\n<p>Fuente: ReconquistaHOY<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La joven madre de Fort\u00edn Olmos fue asesinada el 1 de julio de 2017, hecho por el cual fue condenado a prisi\u00f3n perpetua el profesor Juan Vald\u00e9z. El Gobierno dispuso el pago de un mill\u00f3n de pesos para Gustavo Daniel Monz\u00f3n y a Jos\u00e9 Orlando Stefanucci en virtud de haber aportado &#8220;datos \u00fatiles, relevantes y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":20585,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":{"0":"post-20583","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/20583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=20583"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/20583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/20585"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=20583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=20583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=20583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}