{"id":19255,"date":"2021-04-15T12:24:19","date_gmt":"2021-04-15T15:24:19","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=19255"},"modified":"2021-04-15T12:25:55","modified_gmt":"2021-04-15T15:25:55","slug":"documento-de-la-cgt-por-la-faltante-de-hierro-y-chapa","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/04\/15\/documento-de-la-cgt-por-la-faltante-de-hierro-y-chapa\/","title":{"rendered":"Documento de la CGT por el faltante de hierro y chapa para la construcci\u00f3n"},"content":{"rendered":"<p><strong>En la ma\u00f1ana del 14 de Abril, Aldo Sotelo, Luis Paravano y Andrea Paz, en representaci\u00f3n de la CGT se reunieron v\u00eda Zoom con los concejales de la ciudad para seguir atendiendo la problem\u00e1tica de los precios.<\/strong><\/p>\n<p>Adem\u00e1s estuvieron presentes los empresarios Guillermo Yapur y Daniel Nardelli, junto a varios concejales.<\/p>\n<p><strong>DOCUMENTO<\/strong><\/p>\n<p>Nos qued\u00f3 claro que hay desabastecimiento en varios productos del rubro, pero principalmente en chapa e hierro, y se debe a que en el caso del acero la producci\u00f3n est\u00e1 concentrada en una sola empresa.<\/p>\n<p>Esa posici\u00f3n dominante en el mercado de un insumo imprescindible para el desarrollo de m\u00faltiples actividades, indudablemente que desestabiliza a cualquier gobierno y a cualquier pa\u00eds, por lo tanto hemos pedido al Concejo Deliberante ante esta situaci\u00f3n que haga llegar el reclamo correspondiente para denunciar a los monopolios que atentan contra el bienestar de la poblaci\u00f3n.<\/p>\n<p>Ya estamos imaginando que no se van a poder construir las 200 viviendas que comprometi\u00f3 el Intendente y el Gobierno Provincial para ser destinadas a los trabajadores de esta ciudad y que nosotros esper\u00e1bamos se inicie todo el proceso previo en el segundo semestre de este a\u00f1o. \u201cEs indudable que cuando haya que techarlas se tendr\u00e1 que salir a cortar paja a la isla\u201d.<\/p>\n<p>Antes fueron las reuniones con supermercados y con el Centro Industrial y Comercial, principalmente por la escalada en los alimentos, ahora con los comercios que venden materiales de construcci\u00f3n, ya que el a\u00f1o pasado los precios aumentaron alrededor del 70%.<\/p>\n<p>La construcci\u00f3n, a trav\u00e9s de los programas de viviendas fundamentalmente, es la actividad que mayor cantidad de puestos de trabajo genera, pero si estas irregularidades en el mercado no se corrigen los problemas y las faltantes seguir\u00e1n. Por esa raz\u00f3n y como CGT Regional General Obligado, exigimos que se combata y se sancione severamente a quienes desde sus posiciones dominantes y monop\u00f3licas, causan un gran da\u00f1o a nuestra patria.<\/p>\n<p>Reconquista, 15 de Abril de 2021.<\/p>\n<p>ANDREA PAZ &#8211; ALDO SOTELO &#8211; LUIS PARAVANO &#8211; RAMON ACOSTA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana del 14 de Abril, Aldo Sotelo, Luis Paravano y Andrea Paz, en representaci\u00f3n de la CGT se reunieron v\u00eda Zoom con los concejales de la ciudad para seguir atendiendo la problem\u00e1tica de los precios. Adem\u00e1s estuvieron presentes los empresarios Guillermo Yapur y Daniel Nardelli, junto a varios concejales. DOCUMENTO Nos qued\u00f3 claro [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55],"tags":[],"class_list":["post-19255","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reconquista"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/19255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=19255"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/19255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/19256"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=19255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=19255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=19255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}