{"id":19036,"date":"2021-04-10T10:59:01","date_gmt":"2021-04-10T13:59:01","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=19036"},"modified":"2021-04-10T10:59:01","modified_gmt":"2021-04-10T13:59:01","slug":"elecciones-8-de-agosto-y-24-de-octubre-se-votara-en-santa-fe","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/04\/10\/elecciones-8-de-agosto-y-24-de-octubre-se-votara-en-santa-fe\/","title":{"rendered":"Elecciones: 8 de agosto y 24 de octubre se votar\u00e1 en Santa Fe"},"content":{"rendered":"<p><strong>Se confirmaron las fechas para las elecciones provinciales y se reglament\u00f3 la ley de paridad. <\/strong><strong>Este viernes, el gobernador firm\u00f3 el decreto de convocatoria. Se ratific\u00f3 la decisi\u00f3n de organizar comicios conjuntos con los nacionales, aunque las fechas en esa instancia podr\u00edan modificarse. Adem\u00e1s, se reglament\u00f3 la Ley de Paridad.<\/strong><\/p>\n<p>Respetando el concepto de &#8220;simultaneidad&#8221;, la provincia realiz\u00f3 la convocatoria para las pr\u00f3ximas elecciones en Santa Fe. \u00c9sa es pr\u00e1cticamente la \u00fanica certeza por estas horas, en un escenario nacional plagado todav\u00eda de indefiniciones, e incierto por la coyuntura sanitaria. Pero los plazos vencen. Y a nivel local, la legislaci\u00f3n estipula que antes del 10 de abril, el Poder Ejecutivo tiene que convocar formalmente a los comicios que permitir\u00e1n renovar un pu\u00f1ado de intendencias, todas las comisiones comunales y concejos municipales. El decreto fue firmado este viernes viernes por Omar Perotti.<\/p>\n<p>El ministro de Gobierno, Roberto Sukerman, hab\u00eda adelantado\u00a0a El Litoral que se eval\u00faan &#8220;distintas opciones de redacci\u00f3n&#8221;. Es que si la decisi\u00f3n es realizar comicios conjuntos a los nacionales, la normativa actual establece que las primarias sean el 8 de agosto y las generales el 24 de octubre. Pero eso est\u00e1 en discusi\u00f3n; tanto las fechas puesto que se eval\u00faa un diferimiento del calendario de al menos un mes, como las realizaci\u00f3n misma de las PASO. Ambas instancias obligar\u00edan a que los cambios sean ratificados por ley del Congreso.<\/p>\n<p><strong>Opciones<\/strong><\/p>\n<p>Frente al escenario nacional descripto, Sukerman explicaba que una de las formas que se estudiaban para salvar la situaci\u00f3n en la provincia era plantear un decreto &#8220;gen\u00e9rico&#8221;, que garantice la simultaneidad pero sin especificar fechas. Otra alternativa era convocar expl\u00edcitamente seg\u00fan los d\u00edas ratificados por la C\u00e1mara Electoral Nacional: 8 de agosto y 24 de octubre.<\/p>\n<p>&#8220;En ese caso \u2013 explic\u00f3 el ministro-, si el gobierno central materializa el diferimiento, la provincia prorrogar\u00eda las fechas planteadas en su convocatoria, tal como ya sucedi\u00f3 en 2009. Pero m\u00e1s all\u00e1 de las formas, lo que quedar\u00e1 expresado en el decreto de convocatoria es la decisi\u00f3n pol\u00edtica de realizar elecciones conjuntas con las nacionales&#8221;, enfatiz\u00f3.<\/p>\n<p>Respecto de las primarias, cabe recordar que todos los partidos en Santa Fe rechazaron la posibilidad suspenderlas. La situaci\u00f3n es similar a nivel nacional, pero si en dicha instancia se resolviese no realizarlas, Sukerman explic\u00f3 que \u00e9sa ser\u00eda una discusi\u00f3n que deber\u00eda dar la Legislatura. &#8220;Si las primarias nacionales se suspendieran, la Legislatura tendr\u00eda que resolver qu\u00e9 hace con las PASO provinciales, porque \u00e9sa es una ley provincial. No es algo que podamos resolver nosotros (por decreto)&#8221;, plante\u00f3.<\/p>\n<p>Finalmente, el gobierno provincial opt\u00f3 por explicitar las fechas de las elecciones -8 de agosto y 24 de octubre- y adherir eventualmente a un posterior diferimiento, seg\u00fan lo disponga el gobierno nacional.<\/p>\n<p><strong>Plazos y paridad<\/strong><\/p>\n<p>Seg\u00fan pudo saber El Litoral y en funci\u00f3n de las fechas tentativas que se plantean para las elecciones, el calendario en la provincia estipular\u00eda para el pr\u00f3ximo 30 de mayo la fecha l\u00edmite para la oficializaci\u00f3n de alianzas frente al Tribunal Electoral Provincial. En tanto, el pr\u00f3ximo 4 de junio vencer\u00eda el plazo para la presentaci\u00f3n de listas de candidatos ante las autoridades partidarias.<\/p>\n<p>Fuente: El Litoral<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se confirmaron las fechas para las elecciones provinciales y se reglament\u00f3 la ley de paridad. Este viernes, el gobernador firm\u00f3 el decreto de convocatoria. Se ratific\u00f3 la decisi\u00f3n de organizar comicios conjuntos con los nacionales, aunque las fechas en esa instancia podr\u00edan modificarse. Adem\u00e1s, se reglament\u00f3 la Ley de Paridad. Respetando el concepto de &#8220;simultaneidad&#8221;, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":19037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":{"0":"post-19036","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sin-categoria"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/19036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=19036"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/19036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/19037"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=19036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=19036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=19036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}