{"id":18235,"date":"2021-03-11T19:04:01","date_gmt":"2021-03-11T22:04:01","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=18235"},"modified":"2021-03-11T19:04:01","modified_gmt":"2021-03-11T22:04:01","slug":"preocupacion-de-la-cgt-por-el-aumento-de-los-precios","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/03\/11\/preocupacion-de-la-cgt-por-el-aumento-de-los-precios\/","title":{"rendered":"Preocupaci\u00f3n de la CGT por el aumento de los precios"},"content":{"rendered":"<p><strong>Integrantes de la CGT Regional Departamento General Obligado se reunieron con el intendente municipal Dr. Amadeo Vallejos, a quien le expresaron su preocupaci\u00f3n por el aumento constante de los precios de alimentos y art\u00edculos de primera necesidad en comercios y supermercados de la ciudad.<\/strong><\/p>\n<p>En ese sentido le remarcaron la necesidad de establecer controles oficiales y que se apliquen las sanciones y clausuras que correspondan si hay abusos. Asimismo solicitaron la publicaci\u00f3n de estad\u00edsticas que eval\u00faen mensualmente el comportamiento de los precios y la incidencia del costo mensual de la canasta b\u00e1sica para una familia.<\/p>\n<p>Luego fueron recibidos por autoridades del Centro Industrial y Comercial de Reconquista, estando presentes propietarios de supermercados de la ciudad. All\u00ed se habl\u00f3 largamente acerca de la problem\u00e1tica que afecta a los trabajadores que observan c\u00f3mo van perdiendo poder adquisitivo en su salario. Despu\u00e9s de un extenso intercambio, se decidi\u00f3 concretar un nuevo encuentro a fin de buscar a trav\u00e9s de ofertas y otras estrategias, atemperar la dif\u00edcil situaci\u00f3n que afecta a los sectores asalariados en general, que no pueden acceder a una canasta b\u00e1sica.<\/p>\n<p>Finalmente fueron recibidos en la ma\u00f1ana del mi\u00e9rcoles 10 de marzo por los concejales de la ciudad, con la \u00fanica ausencia de Ignacio Correa. Tambi\u00e9n se intercambiaron ideas entre todos los presentes d\u00f3nde se plantearon iniciativas para lograr el funcionamiento de un mercado municipal que pueda expender al p\u00fablico, la venta de alimentos y otros productos, a precios m\u00e1s beneficiosos para la comunidad.<\/p>\n<p>El Concejo Deliberante se comprometi\u00f3 a convocar a un nuevo encuentro conjunto a la CGT, los comerciantes, los supermercadistas y el Departamento Ejecutivo para abordar entre todos la problem\u00e1tica que expuso la CGT, para buscar atenuar en el bolsillo de los trabajadores, el precio de los productos de consumo masivo. Esta reuni\u00f3n se va a concretar en el curso de la semana pr\u00f3xima.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Integrantes de la CGT Regional Departamento General Obligado se reunieron con el intendente municipal Dr. Amadeo Vallejos, a quien le expresaron su preocupaci\u00f3n por el aumento constante de los precios de alimentos y art\u00edculos de primera necesidad en comercios y supermercados de la ciudad. En ese sentido le remarcaron la necesidad de establecer controles oficiales [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[55],"tags":[],"class_list":["post-18235","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reconquista"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/18235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=18235"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/18235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/18236"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=18235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=18235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=18235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}