{"id":18031,"date":"2021-03-08T09:53:29","date_gmt":"2021-03-08T12:53:29","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=18031"},"modified":"2021-03-09T13:08:51","modified_gmt":"2021-03-09T16:08:51","slug":"vera-celebro-por-ancipiado-el-dia-de-la-mujer","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/03\/08\/vera-celebro-por-ancipiado-el-dia-de-la-mujer\/","title":{"rendered":"Vera celebr\u00f3 por ancipado el D\u00eda de la Mujer"},"content":{"rendered":"<p><strong>En el D\u00eda Internacional de la Mujer, el municipio homenaje\u00f3 y resalt\u00f3 su rol fundamental en la sociedad.<\/strong><\/p>\n<p>&#8220;Una sociedad que de a poco va cambiando el paradigma. Nuestra ciudad es un ejemplo de ese cambio, ya que por primera vez en los 128 a\u00f1os de existencia tenemos una Intendente mujer gracias a la voluntad del verense. Hoy queremos destacar a todas aquellas madres, abuelas, t\u00edas, hermanas, amas de casa, jubiladas y trabajadoras de todos los rubros, incluso de aquellos que parec\u00edan inaccesibles para ellas&#8221;, expresaron desde el gobierno local.<\/p>\n<p>El evento tuvo lugar en el Paseo Ferroviario, con shows art\u00edsticos y feria de artesanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el D\u00eda Internacional de la Mujer, el municipio homenaje\u00f3 y resalt\u00f3 su rol fundamental en la sociedad. &#8220;Una sociedad que de a poco va cambiando el paradigma. Nuestra ciudad es un ejemplo de ese cambio, ya que por primera vez en los 128 a\u00f1os de existencia tenemos una Intendente mujer gracias a la voluntad [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":18034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[53],"tags":[],"class_list":["post-18031","post","type-post","status-publish","format-standard","has-post-thumbnail","category-vera"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/18031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=18031"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/18031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/18034"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=18031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=18031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=18031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}