{"id":17673,"date":"2021-02-24T11:51:31","date_gmt":"2021-02-24T14:51:31","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=17673"},"modified":"2021-02-25T18:44:06","modified_gmt":"2021-02-25T21:44:06","slug":"firme-avance-de-los-cultivos-de-soja-y-de-maiz-tardio","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/02\/24\/firme-avance-de-los-cultivos-de-soja-y-de-maiz-tardio\/","title":{"rendered":"Firme avance de los cultivos de soja y de ma\u00edz tard\u00edo"},"content":{"rendered":"<p><strong>Informe del Sistema de Estimaciones Agr\u00edcolas para el Centro Norte de la Provincia de Santa Fe, correspondiente a la semana comprendida entre el 17 y 21 de febrero de 2021, que difunde la Bolsa de Comercio de Santa Fe.\u00a0<\/strong><\/p>\n<p>Per\u00edodo que comenz\u00f3 con estabilidad clim\u00e1tica, d\u00edas soleados, temperaturas diarias medias aumentando paulatinamente, como as\u00ed tambi\u00e9n la nubosidad, que se increment\u00f3 hacia el final del mismo.<\/p>\n<p>Posteriormente, ingres\u00f3 un frente de tormenta de direcci\u00f3n suroeste-noroeste que provoc\u00f3 inestabilidad clim\u00e1tica, precipitaciones de variadas intensidades (chaparrones), en gran parte del \u00e1rea de estudio y en algunas zonas puntuales se caracteriz\u00f3 por fuertes r\u00e1fagas de viento, cercanas a los 88 km\/h, con da\u00f1os en infraestructuras, ca\u00edda de \u00e1rboles y corte de servicios el\u00e9ctricos, siempre con mayor impacto en las \u00e1reas urbanas.<\/p>\n<p>Los montos pluviom\u00e9tricos acumulados en el per\u00edodo, (hasta las 20 h del 23\/02\/2021) fluctuaron entre 02 y 45 mm, con m\u00e1ximos puntuales de 70, en el oeste del departamento Castellanos, presentando una distribuci\u00f3n geogr\u00e1fica heterog\u00e9nea, en toda la superficie del SEA.<\/p>\n<p>En ella, como consecuencia de los mil\u00edmetros de agua ca\u00eddos y los acumulados, continuaron los encharcamientos \u2013 anegamientos en sectores de posiciones topogr\u00e1ficas bajas, pisos de predios muy h\u00famedos o blandos.<\/p>\n<p>Ante las condiciones ambientales que se describieron en los \u00faltimos cuatro informes, continu\u00f3 observ\u00e1ndose un firme avance de los cultivos agr\u00edcolas de la campa\u00f1a 2020\/2021, recuper\u00e1ndose y consolid\u00e1ndose, especialmente los de soja y de ma\u00edz tard\u00edo, dice el informe del Sistema de Estimaciones Agr\u00edcolas para el Centro Norte de la Provincia de Santa Fe, para la semana comprendida entre el 17 y 23 de febrero de 2021, que difunde la Bolsa de Comercio de Santa Fe.<\/p>\n<p>Dada la \u00f3ptima disponibilidad de agua \u00fatil en los perfiles de los suelos, en un muy alto porcentaje mostraron estados bueno a muy buenos, con lotes excelentes, evidenciando buenas estructuras de plantas, floraci\u00f3n y cantidad de vainas, indicadores que reflejaron, hasta la fecha, todo el potencial gen\u00e9tico de las semillas utilizadas.<\/p>\n<p>GIRASOL<\/p>\n<p>Las condiciones clim\u00e1ticas y el mejoramiento de las condiciones f\u00edsicas de los suelos permitieron avanzar con la cosecha de girasol. Ya se ha trillado el 88% de la superficie sembrada. La cosecha presenta un atraso de 9 puntos en comparaci\u00f3n a similar per\u00edodo de la campa\u00f1a pasada.<\/p>\n<p>Para el \u00e1rea norte del SEA, el rendimiento promedio obtenido fluctu\u00f3 entre los 16 y 18 qq\/ha, d\u00e1ndose por finalizada, en la zona centro, donde en promedio se alcanzaron los 18 \u2013 20 &#8211; 23 qq\/ha, con m\u00e1ximos de 27 qq\/ha, con un 80 % de avance de la trilla y en la zona sur, los rindes oscilaron entre 19 y 21 qq\/ha, con un avance del 70 %.<\/p>\n<p>El enmalezamiento continu\u00f3 siendo el principal inconveniente en los distintos lotes, acrecent\u00e1ndose en el momento de la cosecha.<\/p>\n<p>MA\u00cdZ TEMPRANO<\/p>\n<p>En el \u00e1rea de influencia de las cuencas lecheras del centro \u2013 norte santafesino, el proceso de picado \u2013 embolsado con destino al autoconsumo, se dio por finalizado, representando una superficie de 20.500 ha, unas 2.900 ha, menos que el a\u00f1o pasado y un rendimiento promedio que alcanz\u00f3 entre 11 a 13 m\/bolsa\/ha, considerado por el sector como buenos resultados, en cuanto a calidad y a cantidad.<\/p>\n<p>En los departamentos del norte del SEA, continu\u00f3 el proceso de cosecha del ma\u00edz temprano, sum\u00e1ndose nuevas \u00e1reas, pero el avance del 2 % en la superficie del ma\u00edz temprano con destino comercial de 67.700 ha, estuvo regulada por los porcentajes de humedad de grano, que siguieron siendo altos, reflejando una disminuci\u00f3n con el transcurso de los d\u00edas pero, nuevamente se elevaron ante la inestabilidad clim\u00e1tica que se present\u00f3.<\/p>\n<p>Los primeros datos continuaron mostrando bajos rendimientos que oscilaron entre 45 y 55 qq\/ha, registr\u00e1ndose un grado de avance del 2 % sobre la de la superficie total, con dicho fin.<\/p>\n<p>Los maizales con destino comercial, no variaron sus estados, un 75 % de los cultivares se encontraron de bueno a muy buenos, algunos lotes excelentes, sin inconvenientes para su normal desarrollo, regular un 15 % y un 10 % pas\u00f3 a malo, con marcados s\u00edntomas de estr\u00e9s termo-h\u00eddrico y mortandad de plantas, sin recuperaci\u00f3n.<\/p>\n<p>Los dos \u00faltimos casos, se evidenciaron en mayor proporci\u00f3n, en suelos de aptitudes agr\u00edcolas no ideales o con ciertas limitantes.<\/p>\n<p>ALGOD\u00d3N<\/p>\n<p>Los cultivares de algod\u00f3n expusieron todo su potencial gen\u00e9tico, el 90 % present\u00f3 estado bueno a muy bueno, con lotes excelentes, un 8 % regular y un 2 % malo. Dichas caracter\u00edsticas, fueron el resultado de los diferentes eventos clim\u00e1ticos, que generaron buenas condiciones para el normal crecimiento y siempre, \u00f3ptima disponibilidad de humedad en el perfil de los suelos.<\/p>\n<p>Con el paso de los d\u00edas y las buenas condiciones clim\u00e1ticas comenz\u00f3 la aplicaci\u00f3n de defoliantes en los predios m\u00e1s adelantados, con m\u00e1s del 60 % de c\u00e1psulas abiertas.<\/p>\n<p>SOJA TEMPRANA<\/p>\n<p>En etapas de floraci\u00f3n, comienzo de fructificaci\u00f3n y fructificaci\u00f3n un 95 % de los cultivares de soja temprana presentaron estado bueno a muy bueno, con lotes excelentes, como consecuencia de los cambios de las condiciones clim\u00e1ticas desde la segunda quincena de enero de 2021 hasta la fecha, que fueron muy favorables, un 4 % regular y un 1 % malo, estos \u00faltimos se observaron en suelos con limitantes y menor aptitud agr\u00edcola, con lotes que presentaron cierto marchitamiento por altas temperaturas y no uniformes, manchonados.<\/p>\n<p>Continuaron los intensos monitoreos y evaluaciones de los distintos lotes, la campa\u00f1a estuvo y estar\u00eda caracterizada por la detecci\u00f3n temprana de la presencia de oruga militar (Spodoptera frugiperda) y oruga bolillera (Helicoverpa elotopoeon), generalizadas en toda el \u00e1rea de estudio.<\/p>\n<p>SOJA TARDIA<\/p>\n<p>Los cultivares de soja tard\u00eda continuaron presentando un 80 % estado bueno a muy bueno, con algunos lotes excelentes, un 12 % regular y un 8 % malo. Consolid\u00e1ndose dicha situaci\u00f3n, como<\/p>\n<p>consecuencia de los cambios de las condiciones clim\u00e1ticas desde la segunda quincena de enero del corriente a\u00f1o, hasta la fecha, que fueron favorables para el desarrollo de las etapas vegetativas y las estructuras de las plantas.<\/p>\n<p>Los estados regular y malo, fueron los que no evidenciaron respuestas a las variaciones de las condiciones ambientales mencionadas. En particular, dicha situaci\u00f3n se dio por sectores o \u00e1reas sembradas en suelos con aptitud no agr\u00edcola o con limitantes, que se potenciaron ante contextos l\u00edmites, como d\u00e9ficit o excesos h\u00eddricos.<\/p>\n<p>MA\u00cdZ TARDIO<\/p>\n<p>Los diferentes escenarios clim\u00e1ticos ocurridos, favorecieron el desarrollo y el avance de los estadios fenol\u00f3gicos del ma\u00edz tard\u00edo, expresado en todo su potencial gen\u00e9tico, por ello un 93 % se detect\u00f3 en estado bueno a muy bueno con lotes excelentes, un 3 % regular y un 1 % malo.<\/p>\n<p>En particular, en los departamentos del norte, los cultivares presentaron etapas de crecimiento menos avanzadas que en los departamentos del centro-sur, donde continuaron realiz\u00e1ndose aplicaciones de fertilizantes post emergentes.<\/p>\n<p>Los maizales no evidenciaron inconvenientes sanitarios por plagas o enfermedades.<\/p>\n<p>SORGO GRAN\u00cdFERO<\/p>\n<p>Los cultivares de sorgo gran\u00edfero continuaron presentando un 90 %, estado bueno a muy bueno, sin ning\u00fan inconveniente en su desarrollo. Ante lo enunciado en el informe de la semana pasada, la presencia de una gran poblaci\u00f3n de pulg\u00f3n amarillo o pulg\u00f3n de la ca\u00f1a de az\u00facar (Melanaphis Sacchari), en particular en los departamentos del norte del SEA, se realizaron aplicaciones a\u00e9reas en muchos casos, por la falta de condiciones de los pisos para el ingreso a los lotes o por su estado fenol\u00f3gico. Controles posteriores revelaron buenos resultados, pero deber\u00edan continuar los recorridos y seguimientos peri\u00f3dicos.<\/p>\n<p>AGUA \u00daTIL<\/p>\n<p>En la superficie total del \u00e1rea de estudio, del centro norte santafesino, constituida por los departamentos Nueve de Julio, Vera, General Obligado, San Crist\u00f3bal, San Justo, San Javier, Garay, Castellanos, Las Colonias, La Capital, San Mart\u00edn y San Jer\u00f3nimo, la disponibilidad de agua \u00fatil en los primeros 20 cm de los suelos, se consider\u00f3 \u00f3ptima en general, pero excesiva en \u00e1reas puntuales, con encharcamientos \u2013 anegamientos, en posiciones topogr\u00e1ficas bajas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informe del Sistema de Estimaciones Agr\u00edcolas para el Centro Norte de la Provincia de Santa Fe, correspondiente a la semana comprendida entre el 17 y 21 de febrero de 2021, que difunde la Bolsa de Comercio de Santa Fe.\u00a0 Per\u00edodo que comenz\u00f3 con estabilidad clim\u00e1tica, d\u00edas soleados, temperaturas diarias medias aumentando paulatinamente, como as\u00ed tambi\u00e9n [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51],"tags":[],"class_list":{"0":"post-17673","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/17673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=17673"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/17673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/17674"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=17673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=17673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=17673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}