{"id":17006,"date":"2021-01-21T11:23:31","date_gmt":"2021-01-21T14:23:31","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=17006"},"modified":"2021-01-21T11:23:31","modified_gmt":"2021-01-21T14:23:31","slug":"sosa-se-reunio-con-funcionarios-de-la-provincia-en-el-hospital-regional","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/01\/21\/sosa-se-reunio-con-funcionarios-de-la-provincia-en-el-hospital-regional\/","title":{"rendered":"Sosa se reuni\u00f3 con funcionarios de la provincia en el Hospital Regional"},"content":{"rendered":"<p><strong>En el Hospital de la ciudad de Vera, el senador particip\u00f3 de una reuni\u00f3n con funcionarios del Gobierno de la Provincia, la Subsecretaria de Gesti\u00f3n Territorial, Marcela Flower, el Director de Odontolog\u00eda, Jorge Rodr\u00edguez Zia. Adem\u00e1s, estuvo presente la Directora del Hospital, Beatriz Villa, miembros del equipo de salud y del Consejo Administrativo.<\/strong><\/p>\n<p>El legislador inform\u00f3: &#8220;Conversamos sobre el proceso de vacunaci\u00f3n que se va a implementar en el departamento Vera, con prioridad l\u00f3gicamente del personal de salud, despu\u00e9s seguridad, docentes, para luego seguir con las personas de riesgo e ir avanzando progresivamente en la dem\u00e1s poblaci\u00f3n. En cuanto a la log\u00edstica que necesita el proceso, ya fueron distribuidos en casi todos los distritos del departamento, los distintos freezers para el sistema de refrigeraci\u00f3n.<\/p>\n<p>Otro punto importante es el trabajo y la gesti\u00f3n que viene realizando la Dra. Villa en cuanto a las especialidades que necesita nuestro hospital y las horas para poder cubrir esas especialidades. Un gran avance en ese sentido es la concreci\u00f3n de contar con un otorrinolaring\u00f3logo para el nosocomio, adem\u00e1s, de las gestiones avanzadas para conseguir una neur\u00f3loga, y todo lo relacionado con el equipamiento que necesita el hospital.<\/p>\n<p>Un punto importante es la existencia en el corto plazo de la posibilidad de contar con residencias m\u00e9dicas, convirti\u00e9ndose en un factor importante para nuestro departamento. Tambi\u00e9n analizamos la viabilidad de que en la escuela de enfermer\u00eda pueda surgir todos los a\u00f1os una promoci\u00f3n de la misma.<\/p>\n<p>Otra buena noticia es la anunciada por el gobernador d\u00edas atr\u00e1s de una terapia intensiva, m\u00e1s la casi confirmaci\u00f3n de un cirujano infantil para nuestro hospital.<\/p>\n<p>Es un proyecto ambicioso y esperanzador la de equipar de recursos al Hospital de la ciudad de Vera, y nos entusiasma le direcci\u00f3n de las decisiones pol\u00edticas en salud que se vienen anunciando en el departamento Vera&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el Hospital de la ciudad de Vera, el senador particip\u00f3 de una reuni\u00f3n con funcionarios del Gobierno de la Provincia, la Subsecretaria de Gesti\u00f3n Territorial, Marcela Flower, el Director de Odontolog\u00eda, Jorge Rodr\u00edguez Zia. Adem\u00e1s, estuvo presente la Directora del Hospital, Beatriz Villa, miembros del equipo de salud y del Consejo Administrativo. El legislador [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":17007,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51,53],"tags":[],"class_list":{"0":"post-17006","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales","8":"category-vera"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/17006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=17006"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/17006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/17007"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=17006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=17006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=17006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}