{"id":16754,"date":"2021-01-12T13:00:30","date_gmt":"2021-01-12T16:00:30","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=16754"},"modified":"2021-01-14T14:23:39","modified_gmt":"2021-01-14T17:23:39","slug":"causa-abigeato-calificado-en-una-estacia-sobre-la-ruta-13-serian-inminentes-las-detenciones-de-personas-de-vera","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/01\/12\/causa-abigeato-calificado-en-una-estacia-sobre-la-ruta-13-serian-inminentes-las-detenciones-de-personas-de-vera\/","title":{"rendered":"Causa abigeato calificado en una estancia sobre la Ruta 13: ser\u00edan inminentes las detenciones de personas de Vera"},"content":{"rendered":"<p><strong>En la ma\u00f1ana de hoy, la defensa de la familia Franicevich que ejerce el Estudio del Dr. Sixto Gonz\u00e1lez, solicit\u00f3 audiencia (del Art 280) que opera para aquellos imputados que no han hecho uso de su derecho a declarar al momento de la imputaci\u00f3n fiscal.<\/strong><\/p>\n<p>En ella, uno de los encartados y detenidos preventivamente (Franicevich), involucr\u00f3 como parte de este Abigeato Doblemente Calificado a tres individuos con domicilio en Vera, quienes supuestamente eran los que terminaban haci\u00e9ndose \u201cdel rodeo malhabido\u201d y entregaban a cambio un cheque como pago del bot\u00edn.<\/p>\n<p>Ese t\u00edtulo\/valor a fecha, luego era rescatado por dinero en efectivo al momento de su cargu\u00edo, que practicaba un jaulero de apellido S.<\/p>\n<p>La hacienda era retirada por un sujeto de iniciales A. M., quien a su vez era el librador del documento bancario. Seg\u00fan consta en la confesi\u00f3n de Franicevich, toda esta organizaci\u00f3n estaba perge\u00f1ada en beneficio de un empresario ganadero de la ciudad de Vera.<\/p>\n<p>La fiscal Shirli Tolosa, de la Unidad Fiscal Tostado, cree que se consum\u00f3 una &#8220;asociaci\u00f3n l\u00edcita\u201d y no descart\u00f3 las inminentes \u00f3rdenes de detenci\u00f3n a estos nuevos integrantes en el millonario desfalco, revelaron desde el estudio jur\u00eddico Gonz\u00e1lez.<\/p>\n<p>Por otra parte, el juez de la IPP, Perales, rechaz\u00f3 el pedido de revisi\u00f3n de la cautelar impuesta a los Franicevich y continuar\u00e1n por 90 d\u00edas privados de su libertad.<\/p>\n<p>El caso se inici\u00f3 por la denuncia del productor ganadero Jos\u00e9 An\u00edbal Ass\u00e1n por el robo de 64 vacunos del que fue v\u00edctima en su estancia Isleta Linda, ubicado sobre la Ruta 13 en jurisdicci\u00f3n de 9 de Julio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la ma\u00f1ana de hoy, la defensa de la familia Franicevich que ejerce el Estudio del Dr. Sixto Gonz\u00e1lez, solicit\u00f3 audiencia (del Art 280) que opera para aquellos imputados que no han hecho uso de su derecho a declarar al momento de la imputaci\u00f3n fiscal. En ella, uno de los encartados y detenidos preventivamente (Franicevich), [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[51,30,53],"tags":[],"class_list":{"0":"post-16754","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-locales","8":"category-policiales","9":"category-vera"},"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/16754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=16754"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/16754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/16755"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=16754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=16754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=16754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}