{"id":16543,"date":"2021-01-06T12:30:10","date_gmt":"2021-01-06T15:30:10","guid":{"rendered":"https:\/\/infovera.com.ar\/web\/?p=16543"},"modified":"2021-01-07T11:50:32","modified_gmt":"2021-01-07T14:50:32","slug":"anses-oficializo-la-suspension-del-tramite-de-fe-de-vida-hasta-el-31-de-marzo","status":"publish","type":"post","link":"https:\/\/infovera.com.ar\/web\/2021\/01\/06\/anses-oficializo-la-suspension-del-tramite-de-fe-de-vida-hasta-el-31-de-marzo\/","title":{"rendered":"Anses oficializ\u00f3 la suspensi\u00f3n del tr\u00e1mite de fe de vida hasta el 31 de marzo"},"content":{"rendered":"<p><strong>A trav\u00e9s de la\u00a0Resoluci\u00f3n 442\/2020\u00a0publicada en el Bolet\u00edn Oficial, la ANSES determin\u00f3 que resulta necesario prorrogar la suspensi\u00f3n del tr\u00e1mite de actualizaci\u00f3n de fe de vida <\/strong>por parte de los jubilados y jubiladas y pensionados y pensionadas del Sistema Integrado Previsional Argentino (SIPA) y Pensiones No Contributivas, por los meses de enero, febrero y marzo de 2021.<\/p>\n<p>La medida fue decidida por la directora ejecutiva del organismo,\u00a0Fernanda Raverta, con el fin de garantizarles el cobro de las prestaciones, evitando el traslado de los adultos mayores para realizar el tr\u00e1mite, en el marco de la pandemia por el Covid-19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la\u00a0Resoluci\u00f3n 442\/2020\u00a0publicada en el Bolet\u00edn Oficial, la ANSES determin\u00f3 que resulta necesario prorrogar la suspensi\u00f3n del tr\u00e1mite de actualizaci\u00f3n de fe de vida por parte de los jubilados y jubiladas y pensionados y pensionadas del Sistema Integrado Previsional Argentino (SIPA) y Pensiones No Contributivas, por los meses de enero, febrero y marzo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[62],"tags":[],"class_list":["post-16543","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nacionales"],"_links":{"self":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/16543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/comments?post=16543"}],"version-history":[{"count":0,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/posts\/16543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media\/16544"}],"wp:attachment":[{"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/media?parent=16543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/categories?post=16543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infovera.com.ar\/web\/wp-json\/wp\/v2\/tags?post=16543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}